{"id":6389,"date":"2025-03-01T15:16:32","date_gmt":"2025-03-01T15:16:32","guid":{"rendered":"https:\/\/exploraexpedition.co.za\/tanzania\/"},"modified":"2025-05-18T21:42:39","modified_gmt":"2025-05-18T21:42:39","slug":"tanzania","status":"publish","type":"page","link":"https:\/\/exploraexpedition.co.za\/en\/tanzania\/","title":{"rendered":"TANZANIA"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2b323a&#8221; bg_image=&#8221;994&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;15%&#8221; left_padding_desktop=&#8221;8%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;8%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;hidden&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;81&#8243; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; mobile_disable_bg_image_animation=&#8221;true&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;static&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#f4ece2&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;TANZANIA&#8221; font_size=&#8221;3vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.3&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; url=&#8221;#form&#8221; text=&#8221;Download the program&#8221; css_animation=&#8221;zoomIn&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;percentuale-mobile&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;1&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;3&#8243; phone_cols_flickity=&#8221;2&#8243; flickity_controls=&#8221;none&#8221; color=&#8221;accent-color&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; border_radius=&#8221;none&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;default&#8221; flickity_autorotate_pause_on_hover=&#8221;true&#8221; autorotation_speed=&#8221;4000&#8243;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1747604546532-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1747604546532-7&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Autumn&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Nature and adventure&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221; max_width=&#8221;1000&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#54992f&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;60%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.3&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1747604546601-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1747604546602-5&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Empire-StateBuilding&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Monuments and history&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#ad2e20&#8243; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;5%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.3&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; id=&#8221;1747604546658-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1747604546658-0&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-2&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Slippers&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Relax&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#1e73be&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;20%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;ltr&#8221; font_line_height=&#8221;1.1&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; title=&#8221;Item&#8221; id=&#8221;1747604546716-1&#8243; tab_id=&#8221;1747604546717-8&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Car-3&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Transfers&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#dd9933&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;15%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;ltr&#8221; font_line_height=&#8221;1.1&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;percentuale-desktop&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-1&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Autumn&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Nature and adventure&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221; max_width=&#8221;1000&#8243;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#54992f&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;60%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.3&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Empire-StateBuilding&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Monuments and history&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#ad2e20&#8243; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;5%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1.3&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-2&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Slippers&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Relax&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#1e73be&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;20%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;ltr&#8221; font_line_height=&#8221;1.1&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Extra-Color-3&#8243; icon_padding=&#8221;10px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Car-3&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Transfers&#8221; font_size=&#8221;1.1vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#dd9933&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;15%&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;5vw&#8221; font_size_phone=&#8221;38px&#8221; text_direction=&#8221;ltr&#8221; font_line_height=&#8221;1.1&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; line_reveal_by_space_text_effect=&#8221;none&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;The Great Migration is an extraordinary natural spectacle that takes place every year across the plains of Kenya and Tanzania, involving millions of wildebeests, zebras, and other herbivores. This event, driven by the rainfall cycle, represents a continuous struggle for survival. The animals move through the Serengeti and Maasai Mara reserve in search of greener pastures. During this journey, they not only seek food and water but also sustain the savanna ecosystem, contributing to the growth of grass and providing nourishment to predators such as lions and crocodiles.<br \/>\nOne of the most fascinating and dramatic moments of the migration is the crossing of the Mara River. Between August and September, thousands of animals plunge into its waters, risking their lives due to the numerous predators waiting for them. Many do not survive, but those that make it through emerge stronger, ready to continue their journey towards survival. This crossing is one of the most dangerous, yet also one of the most iconic moments of the Great Migration.<br \/>\nIn addition to being an extraordinary display of strength and resilience, the migration is governed by complex natural laws. The land&#8217;s resources, such as phosphorus, are essential for the females during lactation, making the journey even more challenging.<br \/>\nThe Great Migration offers a breathtaking glimpse into one of the wildest environments in the world, with its survival dynamics being, at times, brutal, leaving an unforgettable impression on anyone who witnesses this magnificent tribute to the strength of nature.<br \/>\n7-day journey.<br \/>\nRequest the program to learn more and join us!&#8221; font_size=&#8221;1.2vw&#8221; font_line_height=&#8221;1.7&#8243; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243; text_direction=&#8221;default&#8221; el_class=&#8221;testo-giustificato&#8221;][\/split_line_heading][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;What is included?&#8221; font_container=&#8221;tag:h5|font_size:16|text_align:left|color:%230a0a0a&#8221; google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][nectar_icon_list animate=&#8221;true&#8221; color=&#8221;default&#8221; direction=&#8221;horizontal&#8221; columns=&#8221;1&#8243; icon_size=&#8221;small&#8221; icon_style=&#8221;border&#8221;][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547128-7&#8243; text=&#8221;Private 4X4 Jeep safari&#8221; icon_fontawesome=&#8221;fa fa-car&#8221; tab_id=&#8221;1747604547128-10&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547140-5&#8243; text=&#8221;Professional guide&#8221; icon_fontawesome=&#8221;fa fa-address-card&#8221; tab_id=&#8221;1747604547140-2&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547147-7&#8243; text=&#8221;All Meals&#8221; icon_fontawesome=&#8221;fa fa-coffee&#8221; tab_id=&#8221;1747604547147-4&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547157-2&#8243; text=&#8221;Accommodations in lodges and hotels&#8221; icon_fontawesome=&#8221;fa fa-bed&#8221; tab_id=&#8221;1747604547157-4&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547167-4&#8243; icon_fontawesome=&#8221;fa fa-tint&#8221; text=&#8221;Mineral water every day&#8221; tab_id=&#8221;1747604547167-7&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547177-6&#8243; text=&#8221;Two bottles of beer per person per day&#8221; icon_fontawesome=&#8221;fa fa-beer&#8221; tab_id=&#8221;1747604547177-9&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547187-7&#8243; icon_fontawesome=&#8221;fa fa-credit-card&#8221; text=&#8221;Taxes \/ IVA&#8221; tab_id=&#8221;1747604547188-9&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547198-10&#8243; icon_fontawesome=&#8221;fa fa-bus&#8221; text=&#8221;All transportation (unless indicated as optional)&#8221; tab_id=&#8221;1747604547199-2&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547205-8&#8243; icon_fontawesome=&#8221;fa fa-child&#8221; text=&#8221;All activities, unless indicated as optional&#8221; tab_id=&#8221;1747604547205-9&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547212-3&#8243; icon_fontawesome=&#8221;fa fa-beer&#8221; text=&#8221;One bottle of wine per day&#8221; tab_id=&#8221;1747604547212-6&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1747604547220-3&#8243; icon_fontawesome=&#8221;fa fa-user-circle&#8221; text=&#8221;Tour leader Explora Expedition&#8221; tab_id=&#8221;1747604547220-4&#8243;][\/nectar_icon_list_item][\/nectar_icon_list][vc_column_text css=&#8221;.vc_custom_1747577753088{margin-top: -8% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p class=\"p1\"><span class=\"s1\"><a href=\"https:\/\/exploraexpedition.co.za\/en\/assicurazione-medico-bagaglio\/\">Information about Medical and Baggage Insurance<\/a><\/span><\/p>\n[\/vc_column_text][vc_custom_heading text=&#8221;How long does the trip last?&#8221; font_container=&#8221;tag:h5|font_size:16|text_align:left|color:%230a0a0a&#8221; google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1747577778765{margin-bottom: 40px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p class=\"p1\">Total duration 7 Days. Request the quote with the complete day-by-day program for free.<\/p>\n[\/vc_column_text][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; url=&#8221;#form&#8221; text=&#8221;Download the program&#8221; css_animation=&#8221;zoomIn&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;7%&#8221; top_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; bottom_padding_tablet=&#8221;-10%&#8221; bottom_padding_phone=&#8221;-10%&#8221; left_padding_phone=&#8221;2%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;2%&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#ad2e20&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;IMMERSE YOURSELF IN THE PHOTOS&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;0.9&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_gallery css=&#8221;&#8221; type=&#8221;flickity_style&#8221; images=&#8221;996,995,994,993,992,991,990&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;large_depth&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#171717&#8243; bg_image=&#8221;910&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]\n<div class=\"roadmap-itinerario-container \" style=\"--dot-color: #f05d5e\">\n    <h2 class=\"roadmap-itinerario-title\">Itinerario<\/h2>\n    \n    <div class=\"roadmap-itinerario-share\">\n        <button class=\"roadmap-share-button\">Condividi <i class=\"fas fa-share-alt\"><\/i><\/button>\n        <button class=\"roadmap-extended-button\">Itinerario esteso <i class=\"fas fa-bars\"><\/i><\/button>\n    <\/div>\n    \n    <div class=\"roadmap-itinerario-timeline\">\n                                    <div class=\"roadmap-day-item \" data-day=\"1\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 1<\/h3>\n                            <p class=\"day-title\">Arrival in Tanzania<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>Expected arrival at Kilimanjaro Airport, where you will meet the TL Explora Expedition team. Afterwards, transfer to Arusha for a relaxing moment at the hotel.<br \/>\nDinner and overnight stay.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                            <div class=\"roadmap-day-item \" data-day=\"2\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 2<\/h3>\n                            <p class=\"day-title\">Tarangire National Park<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>After breakfast, transfer to Tarangire National Park for a safari that will last until late afternoon. Picnic-style packed lunch during the excursion and afternoon safari.<br \/>\nReturn to the lodge in the evening for dinner and overnight stay.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                            <div class=\"roadmap-day-item \" data-day=\"3 - 4\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 3 - 4<\/h3>\n                            <p class=\"day-title\">Serengeti National Park + Southern Serengeti N.P.<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>After an early morning breakfast, departure for the Serengeti, where two days of safari will be dedicated to following the great migration. Picnic-style packed lunch during the excursion. In the evening, accommodation in a lodge camp for dinner and overnight stay.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                            <div class=\"roadmap-day-item \" data-day=\"5\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 5<\/h3>\n                            <p class=\"day-title\">Central Serengeti National Park<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>After breakfast, begin the transfer to the central part of Serengeti National Park. During the day, safari and observation of the migration. Picnic-style packed lunch.<br \/>\nAccommodation in lodge camp for dinner and overnight stay.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                            <div class=\"roadmap-day-item \" data-day=\"6\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 6<\/h3>\n                            <p class=\"day-title\">Ngorongoro Crater<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>After breakfast, departure for the transfer to Ngorongoro Crater. During the day, safari inside the crater and picnic-style packed lunch. In the late afternoon, return to Arusha. Lodge accommodation for dinner and overnight stay.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                            <div class=\"roadmap-day-item \" data-day=\"7\">\n                    <div class=\"roadmap-day-header\">\n                        <div class=\"roadmap-day-dot\"><\/div>\n                        <div class=\"roadmap-day-title\">\n                            <h3>DAY 7<\/h3>\n                            <p class=\"day-title\">End of Expedition<\/p>\n                        <\/div>\n                        <div class=\"roadmap-day-toggle\">\n                            <i class=\"fas fa-chevron-down\"><\/i>\n                        <\/div>\n                    <\/div>\n                    \n                    <div class=\"roadmap-day-content\">\n                                                    <div class=\"roadmap-day-description\">\n                                <p>After breakfast, transfer from the hotel to the airport and conclusion of the expedition.<\/p>\n                            <\/div>\n                                                \n                                                \n                                            <\/div>\n                <\/div>\n                        <\/div>\n<\/div>[vc_custom_heading text=&#8221;Would you like to discover more information? Request the complete program and travel costs&#8221; font_container=&#8221;tag:p|font_size:18|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Roboto%3A100%2C100italic%2C300%2C300italic%2Cregular%2Citalic%2C500%2C500italic%2C700%2C700italic%2C900%2C900italic|font_style:700%20bold%20regular%3A700%3Anormal&#8221; css=&#8221;&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; url=&#8221;#form&#8221; text=&#8221;Download now&#8221; css_animation=&#8221;zoomIn&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;10%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_raw_html css=&#8221;&#8221;]JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZleHBsb3JhZXhwZWRpdGlvbi50cmF2ZWxtYXAubmV0JTJGdGhlLWdyZWF0LW1pZ3JhdGlvbi10YW56YW5pYSUzRm1hcC1vbmx5JTNEMSUyMiUyMHdpZHRoJTNEJTIyMTAwJTI1JTIyJTIwaGVpZ2h0JTNEJTIyNTUwJTIyJTIwZnJhbWVib3JkZXIlM0QlMjIwJTIyJTIwYWxsb3dmdWxsc2NyZWVuJTNFJTNDJTJGaWZyYW1lJTNF[\/vc_raw_html][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; bottom_padding_tablet=&#8221;-10%&#8221; bottom_padding_phone=&#8221;-10%&#8221; left_padding_phone=&#8221;2%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;2%&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#ad2e20&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;DOWNLOAD THE PROGRAM&#8221; font_size=&#8221;3vw&#8221; font_line_height=&#8221;0.9&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#000000&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Fill out the form and you&#8217;ll receive the complete program&#8221; font_size=&#8221;1vw&#8221; font_line_height=&#8221;0.9&#8243; text_direction=&#8221;default&#8221; font_size_tablet=&#8221;18&#8243; font_size_phone=&#8221;16&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6679-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"6679\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/6389#wpcf7-f6679-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"6679\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6679-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:6679,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/>\n<input type=\"hidden\" name=\"redirect_nonce\" value=\"26b973fe51\" \/>\n<input type=\"hidden\" name=\"wpcf7cfpdf_hidden_name\" value=\"document-pdf\" \/>\n<input type=\"hidden\" name=\"wpcf7cfpdf_hidden_reference\" value=\"9bcbba2b\" \/>\n<input type=\"hidden\" name=\"wpcf7cfpdf_hidden_date\" value=\"05132026\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"cf7-flex\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e Cognome*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Messaggio*\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<div class=\"cf7-privacy\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy-consent\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"privacy-consent[]\" value=\"Dichiaro di aver preso visione dell&#039;informativa sulla privacy e acconsento il trattamento dei dati forniti conformemente a quanto previsto.*\" \/><span class=\"wpcf7-list-item-label\">Dichiaro di aver preso visione dell&#039;informativa sulla privacy e acconsento il trattamento dei dati forniti conformemente a quanto previsto.*<\/span><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div class=\"cf7-submit full-width\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner full-width\" type=\"submit\" value=\"invia la richiesta\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2b323a&#8221; bg_image=&#8221;994&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;15%&#8221; left_padding_desktop=&#8221;8%&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6389","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/pages\/6389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/comments?post=6389"}],"version-history":[{"count":3,"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/pages\/6389\/revisions"}],"predecessor-version":[{"id":6587,"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/pages\/6389\/revisions\/6587"}],"wp:attachment":[{"href":"https:\/\/exploraexpedition.co.za\/en\/wp-json\/wp\/v2\/media?parent=6389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}